{"id":10051,"date":"2017-07-27T17:18:25","date_gmt":"2017-07-27T22:18:25","guid":{"rendered":"https:\/\/www.daspetravel.com\/tours\/trek-peru-9-day-adventure\/"},"modified":"2024-03-07T03:05:30","modified_gmt":"2024-03-07T08:05:30","slug":"randonnee-perou-aventure-9-jours","status":"publish","type":"project","link":"https:\/\/daspetravel.com\/fr\/circuits\/randonnee-perou-aventure-9-jours\/","title":{"rendered":"Randonn\u00e9e P\u00e9rou: Aventure de 9 jours"},"content":{"rendered":"<style type=\"text\/css\"> \n#cmsmasters_row_6a046f7c88c355_62677732 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a046f7c88c355_62677732 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 50px; \n} \n\n \n#cmsmasters_tabs_list_item_6a046f7c8a23a a,#cmsmasters_tabs_list_item_6a046f7c8a23a.current_tab a { \n\tbackground-color:#24c358;\n\tborder-color:#24c358;\n} \n #cmsmasters_icon_list_items_6a046f7c896653_69012470 { \n\tcounter-reset:counter_6a046f7c896653_69012470; \n} \n\n#cmsmasters_icon_list_items_6a046f7c896653_69012470 .cmsmasters_icon_list_item { \n\tcounter-increment:counter_6a046f7c896653_69012470; \n} \n\n#cmsmasters_icon_list_items_6a046f7c896653_69012470 .cmsmasters_icon_list_item .cmsmasters_icon_list_icon:before { \n\tcontent:counter(counter_6a046f7c896653_69012470, decimal); \n} \n\n#cmsmasters_icon_list_items_6a046f7c896653_69012470.cmsmasters_icon_list_items .cmsmasters_icon_list_item:before { \n\tleft:33.5px; \n\ttop:68px; \n} \n#cmsmasters_icon_list_items_6a046f7c896653_69012470.cmsmasters_icon_list_type_block .cmsmasters_icon_list_item:before { \n\twidth:1px; \n} \n\n#cmsmasters_icon_list_items_6a046f7c896653_69012470 .cmsmasters_icon_list_icon { \n\twidth:68px; \n\theight:68px; \n\t-webkit-border-radius:50%; \n\tborder-radius:50%; \n} \n\n#cmsmasters_icon_list_items_6a046f7c896653_69012470 .cmsmasters_icon_list_icon:before { \n\tfont-size:30px; \n\tline-height:68px; \n} \n\n#cmsmasters_icon_list_items_6a046f7c896653_69012470 .cmsmasters_icon_list_icon:after { \n\tborder-width:0px; \n\twidth:70px; \n\theight:70px; \n\t-webkit-border-radius:50%; \n\tborder-radius:50%; \n} \n\n.cmsmasters_icon_list_items.cmsmasters_color_type_border #cmsmasters_icon_list_item_6a046f7c897e60_92857533:hover .cmsmasters_icon_list_icon:after { \n\tborder-color:transparent; \n\tborder-width:0; \n} \n\n.cmsmasters_icon_list_items.cmsmasters_color_type_border #cmsmasters_icon_list_item_6a046f7c898c71_80817587:hover .cmsmasters_icon_list_icon:after { \n\tborder-color:transparent; \n\tborder-width:0; \n} \n\n.cmsmasters_icon_list_items.cmsmasters_color_type_border #cmsmasters_icon_list_item_6a046f7c899a23_70418983:hover .cmsmasters_icon_list_icon:after { \n\tborder-color:transparent; \n\tborder-width:0; \n} \n\n.cmsmasters_icon_list_items.cmsmasters_color_type_border #cmsmasters_icon_list_item_6a046f7c89a6e1_69348379:hover .cmsmasters_icon_list_icon:after { \n\tborder-color:transparent; \n\tborder-width:0; \n} \n\n.cmsmasters_icon_list_items.cmsmasters_color_type_border #cmsmasters_icon_list_item_6a046f7c89b478_03855396:hover .cmsmasters_icon_list_icon:after { \n\tborder-color:transparent; \n\tborder-width:0; \n} \n\n.cmsmasters_icon_list_items.cmsmasters_color_type_border #cmsmasters_icon_list_item_6a046f7c89c151_61161906:hover .cmsmasters_icon_list_icon:after { \n\tborder-color:transparent; \n\tborder-width:0; \n} \n\n.cmsmasters_icon_list_items.cmsmasters_color_type_border #cmsmasters_icon_list_item_6a046f7c89d0c6_31246495:hover .cmsmasters_icon_list_icon:after { \n\tborder-color:transparent; \n\tborder-width:0; \n} \n\n.cmsmasters_icon_list_items.cmsmasters_color_type_border #cmsmasters_icon_list_item_6a046f7c89de10_04862245:hover .cmsmasters_icon_list_icon:after { \n\tborder-color:transparent; \n\tborder-width:0; \n} \n\n.cmsmasters_icon_list_items.cmsmasters_color_type_border #cmsmasters_icon_list_item_6a046f7c89ecf1_68205055:hover .cmsmasters_icon_list_icon:after { \n\tborder-color:transparent; \n\tborder-width:0; \n} \n \n#cmsmasters_row_6a046f7c8a4413_28504998 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a046f7c8a4413_28504998 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 50px; \n} \n\n \n#cmsmasters_row_6a046f7c8c0835_60641314 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a046f7c8c0835_60641314 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 50px; \n} \n\n #cmsmasters_icon_list_items_6a046f7c8c2ab1_24326653 { \n\tpadding-left:38px; \n} \n\n#cmsmasters_icon_list_items_6a046f7c8c2ab1_24326653 .cmsmasters_icon_list_item:before { \n\tfont-size:18px; \n\tleft:-38px; \n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8c4578_67709243:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8c51c1_36261393:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8c64d8_19228192:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8c7319_59210913:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8c7dc0_43111811:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8c87b6_45172580:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8c9130_54437123:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8c9c35_88996088:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8ca602_91698030:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8cb0c6_02391634:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8cbaf1_94051093:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8cc486_03629121:before { \n\tcolor:#24c358;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8ccdd3_71061707:before { \n\tcolor:#24c358;\n} \n #cmsmasters_icon_list_items_6a046f7c8ce059_65646174 { \n\tpadding-left:38px; \n} \n\n#cmsmasters_icon_list_items_6a046f7c8ce059_65646174 .cmsmasters_icon_list_item:before { \n\tfont-size:18px; \n\tleft:-38px; \n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8d0152_46422041:before { \n\tcolor:#ff0000;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8d0d18_10938781:before { \n\tcolor:#ff0000;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8d1887_96832753:before { \n\tcolor:#ff0000;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8d2253_59830609:before { \n\tcolor:#ff0000;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8d2fd3_08148908:before { \n\tcolor:#ff0000;\n} \n\n.cmsmasters_icon_list_items #cmsmasters_icon_list_item_6a046f7c8d3a00_29758577:before { \n\tcolor:#ff0000;\n} \n \n#cmsmasters_row_6a046f7c8d40f0_18390355 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a046f7c8d40f0_18390355 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 0px; \n} \n\n<\/style><div id=\"cmsmasters_row_6a046f7c88c355_62677732\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n \n<div class=\"cmsmasters_tabs tabs_mode_tab\">\n<ul class=\"cmsmasters_tabs_list\">\n<li id=\"cmsmasters_tabs_list_item_6a046f7c89252\" class=\"cmsmasters_tabs_list_item current_tab\">\n<a href=\"#\" class=\"cmsmasters-icon-map-2\">\n<span>Principaux attraits<\/span>\n<\/a>\n<\/li><li id=\"cmsmasters_tabs_list_item_6a046f7c89434\" class=\"cmsmasters_tabs_list_item\">\n<a href=\"#\" class=\"cmsmasters-icon-chart-1\">\n<span>Itin\u00e9raire<\/span>\n<\/a>\n<\/li><li id=\"cmsmasters_tabs_list_item_6a046f7c8a0e1\" class=\"cmsmasters_tabs_list_item\">\n<a href=\"#\" class=\"cmsmasters-icon-youtube-play\">\n<span>Video<\/span>\n<\/a>\n<\/li><li id=\"cmsmasters_tabs_list_item_6a046f7c8a23a\" class=\"cmsmasters_tabs_list_item\">\n<a href=\"#\" class=\"cmsmasters-icon-mail-alt\">\n<span>R\u00e9servez!<\/span>\n<\/a>\n<\/li><\/ul>\n<div class=\"cmsmasters_tabs_wrap\">\n<div id=\"cmsmasters_tab_6a046f7c89252\" class=\"cmsmasters_tab active_tab\">\n<div class=\"cmsmasters_tab_inner\">\n<p><strong>Une alternative sans la foule pour une randonn\u00e9e dans les Andes et la Jungle!<\/strong><\/p>\n<p>Ce circuit excitant offre des options de randonn\u00e9e autant dans les Andes p\u00e9ruviennes que dans la jungle dans la r\u00e9gion de Cusco. En combinant un s\u00e9jour dans une maison familiale locale, le camping dans l\u2019une des cha\u00eenes de montagnes les plus impressionnantes du monde, l\u2019exploration de diff\u00e9rents paysages avec une chance unique d\u2019observer la faune p\u00e9ruvienne, ce circuit est recommand\u00e9 pour toute personne avec un go\u00fbt de l\u2019aventure et un d\u00e9sir de voir le P\u00e9rou hors des sentiers battus!<\/p>\n<p>Minimum de participants: 2<\/p>\n<\/div>\n<\/div><div id=\"cmsmasters_tab_6a046f7c89434\" class=\"cmsmasters_tab\">\n<div class=\"cmsmasters_tab_inner\">\n<p>Itin\u00e9raire du circuit<\/p>\n \n<ul id=\"cmsmasters_icon_list_items_6a046f7c896653_69012470\" class=\"cmsmasters_icon_list_items cmsmasters_icon_list_type_block cmsmasters_icon_list_pos_left cmsmasters_color_type_border cmsmasters_icon_list_icon_type_number\"><li id=\"cmsmasters_icon_list_item_6a046f7c897e60_92857533\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon \"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Jour 1: CUSCO<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Profitez d\u2019une journ\u00e9e de repos dans la fascinante ville de Cusco! Il est important de s\u2019acclimater \u00e0 l\u2019altitude avant de d\u00e9buter les parties les plus exigeantes du circuit. Selon votre heure d\u2019arriv\u00e9e, vous pourrez visiter les ruines de Saqsaywaman, le mus\u00e9e de Koricancha et d\u2019autres sites reconnus du centre historique de la ville, o\u00f9 vous pourrez observer un m\u00e9lange d\u2019architecture coloniale et Inca.<\/p>\n<p><em>Altitude maximale:\u00a011155 pi (3400 m) au-dessus du niveau de la mer<\/em><br \/>\n<em>Nuit \u00e0 Cusco<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c898c71_80817587\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon \"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Jour 2: CHINCHERO\u2013 RANDONN\u00c9E HUCHUY QOSQO<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Nous quitterons Cusco aux environs de 6h du matin et nous prendrons la route pour environ 50 minutes vers la ville de Chinchero. Ici, nous visiterons les ruines incas et une \u00e9glise datant du 17<sup>e<\/sup> si\u00e8cle. Nous participerons aussi \u00e0 un atelier int\u00e9ressant d\u2019environ 20 minutes sur les textiles locaux, qui sont pr\u00e9par\u00e9s par les femmes locales de Chinchero. Ces femmes expliqueront comment elles utilisent les plantes locales pour teindre la laine et comment elles travaillent la laine d\u2019alpaca et de mouton.<\/p>\n<p>Par la suite, nous continuerons en voiture pendant environ 45 minutes avant de rejoindre le d\u00e9but du magnifique sentier menant \u00e0 la Vall\u00e9e Sacr\u00e9e des Incas. Nous d\u00e9buterons la marche vers 1 du matin. La plupart du sentier nous am\u00e8ne le long des sentiers originaux utilis\u00e9s par les citoyens de l\u2019Empire Inca; ceci en fait une belle alternative sans la foule au fameux Chemin Inca. Nous passerons par les ruines incas peu fr\u00e9quent\u00e9es de Huchuy Qosqo avant d\u2019atteindre le point de vue \u00e0 partir duquel nous pourrons apercevoir la Vall\u00e9e Sacr\u00e9e. En descendant \u00e0 partir de cet endroit, nous atteindrons le petit village de Lares, o\u00f9 nous passerons la nuit. Lares est une ville magnifique et l\u2019h\u00f4te de quelques sources d\u2019eau chaude naturelles, o\u00f9 nous aurons l\u2019occasion de nous rafra\u00eechir le lendemain matin!<\/p>\n<p>Cette journ\u00e9e est une longue journ\u00e9e de marche et nous pourrons esp\u00e9rer atteindre Lares vers 20:00.<\/p>\n<p><strong>NOTE:<\/strong> <em>Aujourd\u2019hui, le sentier est difficile, particuli\u00e8rement la derni\u00e8re section qui inclut 1 heure de descente abrupte. Vous n\u2019aurez pas besoin de transporter quoi que ce soit, \u00e0 l\u2019exception de votre eau et de vos collations dans un petit sac \u00e0 dos. Tous vos autres articles seront apport\u00e9s pour vous jusqu\u2019\u00e0 la Vall\u00e9e Sacr\u00e9e \u00e0 la fin du trajet.<\/em><\/p>\n<p><em>Temps de marche: 5-6 heures<\/em><br \/>\n<em>Altitude maximale:\u00a013940 pi (4250 m) au-dessus du niveau de la mer<\/em><br \/>\n<em>Nuit \u00e0 Lares (conditions basiques, hostel local)<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c899a23_70418983\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon \"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Jour 3: LARES \u2013 RANDONN\u00c9E VALL\u00c9E PATACANCHA<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Durant la 3<sup>e<\/sup> journ\u00e9e, notre randonn\u00e9e nous am\u00e8nera au travers de diff\u00e9rents paysages et diff\u00e9rentes communaut\u00e9s que nous aurons d\u00e9j\u00e0 exp\u00e9riment\u00e9s! Sur le trajet entre Lares et la Vall\u00e9e de Patacancha, nous pourrons voir de charmantes communaut\u00e9s des Andes, des habitants locaux habill\u00e9s de fa\u00e7on traditionnelle, des tissus color\u00e9s, des troupeaux de lamas et des magnifiques paysages.<\/p>\n<p>Nous quitterons le camp de base de Lares vers 7h (ou plus t\u00f4t, si vous pr\u00e9f\u00e9rez avoir plus de temps dans les sources d\u2019eau chaude) et nous arriverons dans la Vall\u00e9e de Patacancha vers 17:30.<\/p>\n<p>\u00c0 notre arriv\u00e9e \u00e0 Patacancha, vous rencontrerez la famille qui vous logera pour la nuit. L\u2019hospitalit\u00e9 des Andes est unique et vous serez invit\u00e9s \u00e0 joindre la famille pour un repas traditionnel.<\/p>\n<p><em>Temps de march: 8-9 heures<\/em><br \/>\n<em>Altitude maximale: 14760 pi (4500 m) au-dessus du niveau de la mer<\/em><br \/>\n<em>Nuit dans la Vall\u00e9e de Patacancha (conditions vasiques, dans une maison familiale)<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c89a6e1_69348379\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon \"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Jour 4: VALL\u00c9E PATACANCHA \u2013 OLLANTAYTAMBO<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Aujourd\u2019hui, la randonn\u00e9e sera plus courte, mais pas moins spectaculaire. Nous avons quelques options pour modifier la route et rallonger la marche, d\u00e9pendamment de l\u2019envie du groupe.<\/p>\n<p>Nous quitterons le village de la Vall\u00e9e de Patacancha vers 8h du maitn et prendrons le transport pour environ 45 minutes jusqu\u2019au d\u00e9but du sentier.<\/p>\n<p>Durant notre marche, nous passerons au travers des ruines pr\u00e9-incas de Pumamarca, avant d\u2019atteindre la magnifique ville d\u2019Ollantaytambo \u2013 un r\u00e9el gemme de la Vall\u00e9e Sacr\u00e9e \u2013 o\u00f9 nous prendrons du temps pour explorer les ruines incas avec un tour guid\u00e9.<\/p>\n<p><em>Temps de marche: 8 heures + 1 heure dans les ruines d\u2019Ollantaytambo<\/em><br \/>\n<em>Altitude maximale: 14760 pi (4500 m) au-desssu du niveau de la mer<\/em><br \/>\n<em>Nuit \u00e0 Ollantaytambo<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c89b478_03855396\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon \"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Jour 5: OLLANTAYTAMBO \u2013 RANDONN\u00c9E AGUAS CALIENTES<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Durant la cinqui\u00e8me journ\u00e9e, nous traverserons la haute jungle, en exp\u00e9rimentant un climat et un paysage compl\u00e8tement diff\u00e9rent et d\u00e9montrant \u00e0 quel point le P\u00e9rou est diversifi\u00e9!<\/p>\n<p>Nous quitterons Ollantaytambo vers 5.30 du matin et prendrons la route en voiture priv\u00e9e pour environ 4 heures, jusqu\u2019au d\u00e9part du sentier.<\/p>\n<p>La randonn\u00e9e d\u2019aujourd\u2019hui est divis\u00e9e en 2 parties. La premi\u00e8re et la plus belle section nous am\u00e8ne le long d\u2019une partie du Chemin Inca, alors que la seconde nous am\u00e8ne sur une section plane dans la haute jungle. Nous arriverons \u00e0 Aguas Calientes vers 18:00.<\/p>\n<p><em>Temps de marche: 6.5 heures\u00a0<\/em><br \/>\n<em>Altitude maximale: 14170 pi (4320 m) au-dessus du niveau de la mer<\/em><br \/>\n<em>Nuit \u00e0\u00a0Aguas Calientes\u00a0<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c89c151_61161906\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon \"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Jour 6: MACHU PICCHU<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>La sixi\u00e8me journ\u00e9e est\u00a0d\u00e9di\u00e9e \u00e0 l\u2019exploration de la cit\u00e9 Inca perdue du Machu Picchu \u2013 Le site le plus connu du P\u00e9rou! \u00c0 l\u2019int\u00e9rieur des ruines, il y a plusieurs options de disponibles pour vous. Vous pouvez grimper l\u2019une des montagnes, Huayna Picchu ou Machu Picchu, vous pouvez marcher vers la Porte du Soleil (Inti Punku) ou vers le pont Inca.<\/p>\n<p>Vous d\u00e9buterez la visite du Machu Picchu \u00e0 partir d\u2019Aguas Calientes, o\u00f9 vous prendrez un autobus matinal pour atteindre l\u2019entr\u00e9e du site (avec cette option, un frais suppl\u00e9mentaire pour le billet d\u2019autobus sera appliqu\u00e9) ou \u00e0 partir d\u2019o\u00f9 vous d\u00e9buterez la marche (environ 1h-1h30 de marche).<\/p>\n<p>Dans les ruines, vous aurez 2 tours guid\u00e9s, qui vous donneront un apercu de l\u2019histoire et de la culture de l\u2019Empire Inca, ainsi que de l\u2019importance sprituelle, politique et \u00e9ducationnelle du Machu Picchu. Apr\u00e8s le tour, vous aurez le temps d\u2019explorer le site par vous-m\u00eames jusqu\u2019\u00e0 environ 17:00 (vous pouvez aussi quitter plus t\u00f4t si vous le souhaitez).<\/p>\n<p>Apr\u00e8s votre visite, vous retournerez par vous-m\u00eames vers Aguas Calientes par autobus (avec cette option, un frais suppl\u00e9mentaire pour le billet d\u2019autobus sera appliqu\u00e9) ou \u00e0 pieds (environ 1h-1h30 de marche), o\u00f9 vous prendrez le train de retour vers Ollantaytambo. Vous arriverez \u00e0 Ollantaytambo aux environs de 20:20. \u00c0 Ollantaytambo, notre autobus vous attendra afin de vous ramener vers Cusco, o\u00f9 nous arriverons vers 22:30.<\/p>\n<p><em>Altitude maximale: 11154 pi (3400 m)\u00a0au-dessus de la mer<\/em><br \/>\n<em>Nuit \u00e0 Cusco<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c89d0c6_31246495\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon \"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Jour 7: RANDONN\u00c9E AUSANGATE (COURT CIRCUIT)<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Apr\u00e8s un lev\u00e9 vers 4:45 am, nous prendrons la voiture pour environ 4 heures afin de rejoindre la r\u00e9gion de Ausangate, o\u00f9 nous d\u00e9buterons notre randonn\u00e9e d\u2019une journ\u00e9e vers les 7 lacs d\u2019Ausangate. Sur la route, nous arr\u00eaterons pour un d\u00e9jeuner p\u00e9ruvien servi dans la rue! La randonn\u00e9e prendra environ 8-9 heures, au travers des paysages spectaculaires de la r\u00e9gion d\u2019Ausangate, o\u00f9 nous pourrons apercevoir des troupeaux d\u2019alpacas et les incroyables sommets enneig\u00e9s, incluant le mont Ausangate \u2013 le plus haut sommet de la r\u00e9gion de Cusco. \u00c0 cet endroit, nous serons \u00e0 une altitude de 15910 pi (4850 m) \u2013 le plus haut point de notre randonn\u00e9e!\u00a0Nous pourrons d\u00e9guster notre d\u00eener \u00e0 l\u2019une des parties les plus impressionnantes du sentier, o\u00f9 nous aurons une vue imprenable sur les sommets de la Cordilli\u00e8re Vilcanota.<\/p>\n<p>Nous terminerons la randonn\u00e9e ver 17:30, o\u00f9 nous serons ramen\u00e9s en voiture vers Cusco, apr\u00e8s un trajet d\u2019environ 4 heures, o\u00f9 nous arriverons vers 21:00.<\/p>\n<p><em>Temps de marche: 8-9 heures\u00a0<\/em><br \/>\n<em>Altitude maximale: 15910 pi (4850 m) au-dessus du niveau de la mer<\/em><br \/>\n<em>Nuit dans une famille locale, hostel basique pr\u00e8s de Checacupe\u00a0<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c89de10_04862245\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon \"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Jour 8: RAINBOW MOUNTAIN \u2013 RANDONN\u00c9E PALCOYO<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Aujourd\u2019hui, nous nous rendrons jusqu\u2019aux magnifiques \u00ab\u00a0Rainbow Mountains\u00a0\u00bb, apr\u00e8s avoir quitt\u00e9s notre hostel vers 77h du matin.<\/p>\n<p>La marche vers la montagne est difficile, mais magnifique et vous am\u00e8ne jusqu\u2019\u00e0 un impressionnant 16400 pi (5000 m) au-dessus du niveau de la mer! \u00c0 ce moment, vous devriez \u00eatre compl\u00e8tement acclimat\u00e9s \u00e0 l\u2019altitude et en mesure de relaxer et de profiter des vues fantastiques.<\/p>\n<p>Notre transport priv\u00e9 nous ram\u00e8nera vers Cusco en soir\u00e9e, o\u00f9 vous aurez du temps pour relaxer \u00e0 votre h\u00f4tel et pour explorer la vie nocturne.<\/p>\n<p><em>Temps de marche: 1-2 heures\u00a0<\/em><br \/>\n<em>Altitude maximale: 16400 pi (5000 m) au-dessus du niveau de la mer<\/em><br \/>\n<em>Nuit \u00e0 Cusco<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c89ecf1_68205055\" class=\"cmsmasters_icon_list_item\">\n<div class=\"cmsmasters_icon_list_item_inner\">\n<div class=\"cmsmasters_icon_list_icon_wrap\">\n<span class=\"cmsmasters_icon_list_icon \"><\/span>\n<\/div>\n<div class=\"cmsmasters_icon_list_item_content\">\n<h4 class=\"cmsmasters_icon_list_item_title\">Jour 9: CUSCO<\/h4>\n<div class=\"cmsmasters_icon_list_item_text\">\n<p>Journ\u00e9e de repos \u00e0 Cusco.<\/p>\n<p>Selon votre heure de d\u00e9part de Cusco, vous aurez peut-\u00eatre un peu de temps suppl\u00e9mentaire pour visiter d\u2019autres sites de la ville, errer dans les march\u00e9s ou vous arr\u00eater pour un repas traditionnel au march\u00e9 San Pedro!<\/p>\n<p><em>Altitude maximale: 11154 pi (3400 m)\u00a0au-dessus du niveau de la mer<\/em><\/p>\n<p><strong>Votre circuit \u201cRandonn\u00e9e P\u00e9rou: Aventure de 9 jours\u201d se terminera \u00e0 Cusco. Si vous souhaitez rester plus longtemps dans la r\u00e9gion de Cusco ou dans toutes autres r\u00e9gions du P\u00e9rou, n&rsquo;h\u00e9sitez-pas \u00e0 nous contacter. Nous nous ferons un plaisir de modifier nos circuits afin qu&rsquo;ils r\u00e9pondent \u00e0 vos go\u00fbts et vos attentes. <\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/li><\/ul>\n<\/div>\n<\/div><div id=\"cmsmasters_tab_6a046f7c8a0e1\" class=\"cmsmasters_tab\">\n<div class=\"cmsmasters_tab_inner\">\n<iframe loading=\"lazy\" title=\"Trek Peru 9 Day Adventure\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Xk8-5cCpnq8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div>\n<\/div><div id=\"cmsmasters_tab_6a046f7c8a23a\" class=\"cmsmasters_tab\">\n<div class=\"cmsmasters_tab_inner\">\n<div class=\"cmsmasters_contact_form\">[cmsmasters_contact_form_sc formname=\"4243\" email=\"erhaer4\" fromname=\"wordpress\"]<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a046f7c8a4413_28504998\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<p><script type=\"text\/javascript\">jQuery(document).ready(function () { jQuery(\"#cmsmasters_hover_slider_6a046f7c8a72d\").cmsmastersHoverSlider( { sliderBlock : \"#cmsmasters_hover_slider_6a046f7c8a72d\", sliderItems : \".cmsmasters_hover_slider_items\", thumbWidth : \"100\", thumbHeight : \"60\", activeSlide : 1, pauseTime : 5000, pauseOnHover : true } );} );<\/script><div id=\"cmsmasters_hover_slider_6a046f7c8a72d\" class=\"cmsmasters_hover_slider\">\n<ul class=\"cmsmasters_hover_slider_items\">\n<li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"496\" src=\"https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Peruvian-Rainbow-Mountains.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt=\"Three Rainbow Mountains Palcoyo and Rafting Tour\" srcset=\"https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Peruvian-Rainbow-Mountains.jpg 860w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Peruvian-Rainbow-Mountains-600x346.jpg 600w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Peruvian-Rainbow-Mountains-300x173.jpg 300w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Peruvian-Rainbow-Mountains-768x443.jpg 768w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Peruvian-Rainbow-Mountains-580x335.jpg 580w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"496\" src=\"https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-in-Patacancha-valley-Peru-tailor-made-holiday-1.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt=\"\" srcset=\"https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-in-Patacancha-valley-Peru-tailor-made-holiday-1.jpg 860w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-in-Patacancha-valley-Peru-tailor-made-holiday-1-600x346.jpg 600w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-in-Patacancha-valley-Peru-tailor-made-holiday-1-300x173.jpg 300w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-in-Patacancha-valley-Peru-tailor-made-holiday-1-768x443.jpg 768w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-in-Patacancha-valley-Peru-tailor-made-holiday-1-580x335.jpg 580w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"496\" src=\"https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Ollantaytambo-Inca-ruins-Peru-tailor-made-holiday.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt=\"Ollantaytambo\" srcset=\"https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Ollantaytambo-Inca-ruins-Peru-tailor-made-holiday.jpg 860w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Ollantaytambo-Inca-ruins-Peru-tailor-made-holiday-600x346.jpg 600w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Ollantaytambo-Inca-ruins-Peru-tailor-made-holiday-300x173.jpg 300w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Ollantaytambo-Inca-ruins-Peru-tailor-made-holiday-768x443.jpg 768w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Ollantaytambo-Inca-ruins-Peru-tailor-made-holiday-580x335.jpg 580w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"496\" src=\"https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Rainbow-Mountains-in-Peru.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt=\"Three Rainbow Mountains Palcoyo and Rafting Tour\" srcset=\"https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Rainbow-Mountains-in-Peru.jpg 860w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Rainbow-Mountains-in-Peru-600x346.jpg 600w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Rainbow-Mountains-in-Peru-300x173.jpg 300w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Rainbow-Mountains-in-Peru-768x443.jpg 768w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/08\/Rainbow-Mountains-in-Peru-580x335.jpg 580w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/figure><\/li><li><figure class=\"cmsmasters_hover_slider_full_img\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"496\" src=\"https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-Ausangate-Cusco-tours-2.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail\" alt=\"\" srcset=\"https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-Ausangate-Cusco-tours-2.jpg 860w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-Ausangate-Cusco-tours-2-600x346.jpg 600w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-Ausangate-Cusco-tours-2-300x173.jpg 300w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-Ausangate-Cusco-tours-2-768x443.jpg 768w, https:\/\/daspetravel.com\/wp-content\/uploads\/2017\/07\/Trekking-Ausangate-Cusco-tours-2-580x335.jpg 580w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/figure><\/li><\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a046f7c8c0835_60641314\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_half\">\n \n<ul id=\"cmsmasters_icon_list_items_6a046f7c8c2ab1_24326653\" class=\"cmsmasters_icon_list_items cmsmasters_icon_list_type_list cmsmasters_icon_list_pos_left cmsmasters_color_type_border\"><li id=\"cmsmasters_icon_list_item_6a046f7c8c3ab5_52560619\" class=\"cmsmasters_icon_list_item cmsmasters-icon-spinner\">INCLUS<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8c4578_67709243\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">Guide parlant anglais et espagnol<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8c51c1_36261393\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">H\u00e9bergement: 8 nuits<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8c64d8_19228192\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">8 x D\u00e9jeuner<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8c7319_59210913\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">\u00c9quipement de camping (Tente et matelas)<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8c7dc0_43111811\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">Entr\u00e9e au Parc Ausangate<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8c87b6_45172580\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">Entr\u00e9e aux ruines Huchuy Qosqo <\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8c9130_54437123\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">Entr\u00e9e aux bains thermaux de Santa Teresa<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8c9c35_88996088\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">Entr\u00e9e au Machu Picchu<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8ca602_91698030\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">Entr\u00e9e aux ruines incas d\u2032Ollantaytambo<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8cb0c6_02391634\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">Entr\u00e9e aux bains thermaux de Lares<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8cbaf1_94051093\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">Entr\u00e9e aux Rainbow Mountains de Palcoyo<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8cc486_03629121\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">Train Ollantaytambo-Aguas Calientes (all\u00e9e)<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8ccdd3_71061707\" class=\"cmsmasters_icon_list_item cmsmasters-icon-check-1\">Transport priv\u00e9 vers les attractions<\/li><\/ul>\n<\/div>\n<div class=\"cmsmasters_column one_half\">\n \n<ul id=\"cmsmasters_icon_list_items_6a046f7c8ce059_65646174\" class=\"cmsmasters_icon_list_items cmsmasters_icon_list_type_list cmsmasters_icon_list_pos_left cmsmasters_color_type_border\"><li id=\"cmsmasters_icon_list_item_6a046f7c8cf476_55344429\" class=\"cmsmasters_icon_list_item cmsmasters-icon-spinner\">EXCLUS<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8d0152_46422041\" class=\"cmsmasters_icon_list_item cmsmasters-icon-cancel-2\">D\u00eener et Souper (sauf si sp\u00e9cifi\u00e9 dans l\u2032itin\u00e9raire)<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8d0d18_10938781\" class=\"cmsmasters_icon_list_item cmsmasters-icon-cancel-2\">Assurance voyage (obligatoire)<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8d1887_96832753\" class=\"cmsmasters_icon_list_item cmsmasters-icon-cancel-2\">Pourboire<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8d2253_59830609\" class=\"cmsmasters_icon_list_item cmsmasters-icon-cancel-2\">Sac de couchage et \u00e9quipement de camping extra<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8d2fd3_08148908\" class=\"cmsmasters_icon_list_item cmsmasters-icon-cancel-2\">Autobus Aguas Calientes-Machu Picchu (all\u00e9e-retour)<\/li><li id=\"cmsmasters_icon_list_item_6a046f7c8d3a00_29758577\" class=\"cmsmasters_icon_list_item cmsmasters-icon-cancel-2\">Acc\u00e8s aux montagnes optionnelles: le Huayna Picchu ou le Machu Picchu<\/li><\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a046f7c8d40f0_18390355\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_text\">\n<p>Before booking any tour we require all clients to carefully consult our\u00a0<a href=\"\/?page_id=13805\"><strong>Terms<\/strong><\/a>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00eats pour un d\u00e9fi? Notre circuit Randonn\u00e9e P\u00e9rou: Aventure de 9 jours est une excursion qui vous am\u00e8ne au travers des sections les plus belles mais les plus exigeantes des Andes, de l&rsquo;ancien Chemin Inca aux sentiers vierges! <\/p>\n","protected":false},"author":1,"featured_media":10810,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"footnotes":""},"pj-categs":[692,683,682,680,697],"pj-tags":[715,750,705,749],"class_list":["post-10051","project","type-project","status-publish","format-standard","has-post-thumbnail","hentry","pj-categs-actif","pj-categs-cusco-fr","pj-categs-forfaits-de-circuit","pj-categs-populaire","pj-categs-randonnee","pj-tags-cusco-region-tours-fr","pj-tags-hiking-fr","pj-tags-machu-picchu-tour-fr","pj-tags-trekking-fr"],"_links":{"self":[{"href":"https:\/\/daspetravel.com\/fr\/wp-json\/wp\/v2\/project\/10051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daspetravel.com\/fr\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/daspetravel.com\/fr\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/daspetravel.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/daspetravel.com\/fr\/wp-json\/wp\/v2\/comments?post=10051"}],"version-history":[{"count":0,"href":"https:\/\/daspetravel.com\/fr\/wp-json\/wp\/v2\/project\/10051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/daspetravel.com\/fr\/wp-json\/wp\/v2\/media\/10810"}],"wp:attachment":[{"href":"https:\/\/daspetravel.com\/fr\/wp-json\/wp\/v2\/media?parent=10051"}],"wp:term":[{"taxonomy":"pj-categs","embeddable":true,"href":"https:\/\/daspetravel.com\/fr\/wp-json\/wp\/v2\/pj-categs?post=10051"},{"taxonomy":"pj-tags","embeddable":true,"href":"https:\/\/daspetravel.com\/fr\/wp-json\/wp\/v2\/pj-tags?post=10051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}